{"id":884,"date":"2018-09-14T14:50:03","date_gmt":"2018-09-14T12:50:03","guid":{"rendered":"https:\/\/www.almliebe.com\/blog\/?p=884"},"modified":"2018-11-01T13:16:14","modified_gmt":"2018-11-01T12:16:14","slug":"die-wiesn-trends-2018-fuer-maenner","status":"publish","type":"post","link":"https:\/\/www.almliebe.com\/blog\/2018\/09\/die-wiesn-trends-2018-fuer-maenner\/","title":{"rendered":"Die Wiesn Trends 2018 f\u00fcr M\u00e4nner"},"content":{"rendered":"<p>Wer denkt in der M\u00e4nner Tracht gibt es keine Ver\u00e4nderung, liegt falsch. Lederhose, Hemd, Gilet haben sich zwar weitgehend durchgesetzt. Aber die Feinheiten machen den Unterschied!<\/p>\n<h3>Wiesn-Trend Nr 1: Graustichige Lederhosen<\/h3>\n<p>Nachdem sich die kurze Lederhose bis zum Knie eindeutig durchgesetzt hat, kann man sich nur noch \u00fcber Qualit\u00e4t und Farbe abheben. Ganz klar im Trend sind leicht graustichige Ledert\u00f6ne. Nicht zu plakativ und platt. Aber sowohl bei dunklen als auch bei helleren Lederhosen geht die Tendenz weg vom Braun zu k\u00fchleren Graut\u00f6nen. Coole Varianten davon gibt es von unserem \u00f6sterreichischen Hersteller Ostarrichi und der bayerischen Traditionsmanufaktur Meindl.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-888\" src=\"https:\/\/www.almliebe.com\/blog\/wp-content\/uploads\/2018\/09\/AL_HW1819_CORTELLESI_0065.jpeg\" alt=\"\" width=\"854\" height=\"1280\" srcset=\"https:\/\/www.almliebe.com\/blog\/wp-content\/uploads\/2018\/09\/AL_HW1819_CORTELLESI_0065.jpeg 854w, https:\/\/www.almliebe.com\/blog\/wp-content\/uploads\/2018\/09\/AL_HW1819_CORTELLESI_0065-200x300.jpeg 200w, https:\/\/www.almliebe.com\/blog\/wp-content\/uploads\/2018\/09\/AL_HW1819_CORTELLESI_0065-768x1151.jpeg 768w, https:\/\/www.almliebe.com\/blog\/wp-content\/uploads\/2018\/09\/AL_HW1819_CORTELLESI_0065-683x1024.jpeg 683w\" sizes=\"auto, (max-width: 854px) 100vw, 854px\" \/><\/p>\n<h3>Wiesn-Trend Nr. 2: Uni und Streifen Hemden<\/h3>\n<p>Es ist einfach wirklich so: Karohemden sind sowas von out M\u00e4nner! Zumindest die alten gro\u00dfkarierten in blau oder rot. Lieber kleinkariert hei\u00dft es bei den Hemden. Und nur von coolen Herstellern wie Gottseidank. Ansonsten lieber zum schlichten wei\u00dfen Hemd mit Stehkragen greifen oder zu dezenten Streifenhemden von Gottseidank, Pure oder Almliebe. Wichtig: Zum hochgekn\u00f6pften Gilet passt eigentlich nur das Stehkragenhemd. Und nat\u00fcrlich Slim Fit.<\/p>\n<h3>Wiesn-Trend Nr. 3: Festliche Gilets<\/h3>\n<p>Zumindest zu festlichen Anl\u00e4ssen wie die Wiesn oder anderen Volksfesten ist das Gilet ein Must-Have. Die Hauptmarken bei den edlen traditionellen Westen sind Gottseidank, Grasegger und Hammerschmid. Ob aus klassischem Loden oder Jaquard-Stoffen, Hauptsache es glitzert nicht zu stark. Vor allem auch nicht am R\u00fcckenteil. Zu seidige Westen oder grelle Farben sind out. Aufsteiger ist das Gilet mit V-Ausschnitt.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-892\" src=\"https:\/\/www.almliebe.com\/blog\/wp-content\/uploads\/2018\/09\/AL_HW1819_CORTELLESI_0892.jpeg\" alt=\"\" width=\"854\" height=\"1280\" srcset=\"https:\/\/www.almliebe.com\/blog\/wp-content\/uploads\/2018\/09\/AL_HW1819_CORTELLESI_0892.jpeg 854w, https:\/\/www.almliebe.com\/blog\/wp-content\/uploads\/2018\/09\/AL_HW1819_CORTELLESI_0892-200x300.jpeg 200w, https:\/\/www.almliebe.com\/blog\/wp-content\/uploads\/2018\/09\/AL_HW1819_CORTELLESI_0892-768x1151.jpeg 768w, https:\/\/www.almliebe.com\/blog\/wp-content\/uploads\/2018\/09\/AL_HW1819_CORTELLESI_0892-683x1024.jpeg 683w\" sizes=\"auto, (max-width: 854px) 100vw, 854px\" \/><\/p>\n<h3>Wiesn-Trend Nr. 4: Das Trachtensakko<\/h3>\n<p>Wer noch eins draufsetzen will, der tr\u00e4gt diese Saison schneidige Trachten-Sakkos von Gottseidank, Amsel oder Grasegger. Schmal geschnittene Sakkos in grau, gr\u00fcn oder blau aus Loden sind das edelste Accessoire des Mannes und zeigen: Der Mann liebt Tracht und hat Stil!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-889\" src=\"https:\/\/www.almliebe.com\/blog\/wp-content\/uploads\/2018\/09\/AL_HW1819_CORTELLESI_0423.jpeg\" alt=\"\" width=\"1280\" height=\"854\" srcset=\"https:\/\/www.almliebe.com\/blog\/wp-content\/uploads\/2018\/09\/AL_HW1819_CORTELLESI_0423.jpeg 1280w, https:\/\/www.almliebe.com\/blog\/wp-content\/uploads\/2018\/09\/AL_HW1819_CORTELLESI_0423-300x200.jpeg 300w, https:\/\/www.almliebe.com\/blog\/wp-content\/uploads\/2018\/09\/AL_HW1819_CORTELLESI_0423-768x512.jpeg 768w, https:\/\/www.almliebe.com\/blog\/wp-content\/uploads\/2018\/09\/AL_HW1819_CORTELLESI_0423-1024x683.jpeg 1024w, https:\/\/www.almliebe.com\/blog\/wp-content\/uploads\/2018\/09\/AL_HW1819_CORTELLESI_0423-120x80.jpeg 120w, https:\/\/www.almliebe.com\/blog\/wp-content\/uploads\/2018\/09\/AL_HW1819_CORTELLESI_0423-255x170.jpeg 255w, https:\/\/www.almliebe.com\/blog\/wp-content\/uploads\/2018\/09\/AL_HW1819_CORTELLESI_0423-345x230.jpeg 345w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<h3>Wiesn-Trend Nr. 5: Gscheide Schuah<\/h3>\n<p>Liebe M\u00e4nner, ihr k\u00f6nnt noch so ein tolles Wiesn-Outfit tragen. Wenn ihr h\u00e4ssliche Schuhe anhabt, ist alles zerst\u00f6rt und umsonst. Also, gscheide klassische Haferlschuhe kaufen, am besten von Meindl oder Dirndl&amp;Bua und in schwarz. Alternative sind eigentlich nur halbhohe berginspirierte Schuhe wie der <a href=\"https:\/\/www.almliebe.com\/dirndl-bua-herren-schuhe-6515-hirsch-tabacco.html\" target=\"_blank\" rel=\"noopener\">Hirsch Tabacco von Dirndl&amp;Bua<\/a>: Oder ausnahmsweise mal besonders coole Sneaker. Aber eigentlich dann auch eher im Biergarten und nicht im Festzelt.<\/p>\n<h3>Wiesn-Trend Nr. 6: Cleane Strickjanker<\/h3>\n<p>Der schmale Strickjanker von Gottseidank aus 100% Schurwolle bleibt der Liebling der M\u00e4nner. Ein bisschen leichter und nicht so warm ist der Strickjanker \u201eAloisius\u201c der perfekte Begleiter f\u00fcr den Hin- und (hoffentlich) Nachhauseweg. In der schmal geschnittenen cleanen Strickjacke macht jeder eine gute Figur. Die Gefahr Strickjacken zu verlieren ist immer gegeben. Trotzdem unbedingt die sch\u00f6nsten Outfits zur Wiesn Tragen. Wann denn sonst?<\/p>\n<h3>Wiesn-Trend Nr. 7: Kniestr\u00fcmpfe<\/h3>\n<p>Loaferl (Strumpf-Zweiteiler aus F\u00fcsslingen und Wadlschoner) sind ohne Frage traditionell. Aber auch ein bisschen out. Die informierten coolen Typen tragen lange Kniestr\u00fcmpfe, am besten die \u201eLoisach\u201c oder \u201ePartnach\u201c von Gottseidank. Farblich abgestimmt zum Outfit in Gr\u00fcn oder Blau oder zeitlos und klassisch in Grau.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wer denkt in der M\u00e4nner Tracht gibt es keine Ver\u00e4nderung, liegt falsch. Lederhose, Hemd, Gilet haben sich zwar weitgehend durchgesetzt. Aber die Feinheiten machen den Unterschied! Wiesn-Trend Nr 1: Graustichige Lederhosen Nachdem sich die kurze Lederhose bis zum Knie eindeutig durchgesetzt hat, kann man sich nur noch \u00fcber Qualit\u00e4t und Farbe abheben. Ganz klar im Trend sind leicht graustichige Ledert\u00f6ne. Nicht zu plakativ und platt. Aber sowohl bei dunklen als auch bei helleren Lederhosen geht die Tendenz weg vom Braun zu k\u00fchleren Graut\u00f6nen. Coole Varianten davon gibt es von unserem \u00f6sterreichischen Hersteller Ostarrichi und der bayerischen Traditionsmanufaktur Meindl. Wiesn-Trend Nr. 2: Uni und Streifen Hemden Es ist einfach wirklich so: Karohemden sind sowas von out M\u00e4nner! Zumindest die alten gro\u00dfkarierten in blau oder rot. Lieber kleinkariert hei\u00dft es bei den Hemden. Und nur von coolen Herstellern wie Gottseidank. Ansonsten lieber zum schlichten wei\u00dfen Hemd mit Stehkragen greifen oder zu dezenten Streifenhemden von Gottseidank, Pure oder Almliebe. Wichtig: Zum hochgekn\u00f6pften Gilet passt eigentlich nur das Stehkragenhemd. Und nat\u00fcrlich Slim Fit. Wiesn-Trend Nr. 3: Festliche Gilets Zumindest zu festlichen Anl\u00e4ssen wie die Wiesn oder anderen Volksfesten ist das Gilet ein Must-Have. Die Hauptmarken bei den edlen traditionellen Westen sind Gottseidank, Grasegger und Hammerschmid. Ob aus klassischem Loden oder Jaquard-Stoffen, Hauptsache es glitzert nicht zu stark. Vor allem auch nicht am R\u00fcckenteil. Zu seidige Westen oder grelle Farben sind out. Aufsteiger ist das Gilet mit V-Ausschnitt. Wiesn-Trend Nr. 4: Das Trachtensakko Wer noch eins draufsetzen will, der tr\u00e4gt diese Saison schneidige Trachten-Sakkos von Gottseidank, Amsel oder Grasegger. Schmal geschnittene Sakkos in grau, gr\u00fcn oder blau aus Loden sind das edelste Accessoire des Mannes und zeigen: Der Mann liebt Tracht und hat Stil! Wiesn-Trend Nr. 5: Gscheide Schuah Liebe M\u00e4nner, ihr k\u00f6nnt noch so ein tolles Wiesn-Outfit tragen. Wenn ihr h\u00e4ssliche Schuhe anhabt, ist alles zerst\u00f6rt und umsonst. Also, gscheide klassische Haferlschuhe kaufen, am besten von Meindl oder Dirndl&amp;Bua und in schwarz. Alternative sind eigentlich nur halbhohe berginspirierte Schuhe wie der Hirsch Tabacco von Dirndl&amp;Bua: Oder ausnahmsweise mal besonders coole Sneaker. Aber eigentlich dann auch eher im Biergarten und nicht im Festzelt. Wiesn-Trend Nr. 6: Cleane Strickjanker Der schmale Strickjanker von Gottseidank aus 100% Schurwolle bleibt der Liebling der M\u00e4nner. Ein bisschen leichter und nicht so warm ist der Strickjanker \u201eAloisius\u201c der perfekte Begleiter f\u00fcr den Hin- und (hoffentlich) Nachhauseweg. In der schmal geschnittenen cleanen Strickjacke macht jeder eine gute Figur. Die Gefahr Strickjacken zu verlieren ist immer gegeben. Trotzdem unbedingt die sch\u00f6nsten Outfits zur Wiesn Tragen. Wann denn sonst? Wiesn-Trend Nr. 7: Kniestr\u00fcmpfe Loaferl (Strumpf-Zweiteiler aus F\u00fcsslingen und Wadlschoner) sind ohne Frage traditionell. Aber auch ein bisschen out. Die informierten coolen Typen tragen lange Kniestr\u00fcmpfe, am besten die \u201eLoisach\u201c oder \u201ePartnach\u201c von Gottseidank. Farblich abgestimmt zum Outfit in Gr\u00fcn oder Blau oder zeitlos und klassisch in Grau.<\/p>\n","protected":false},"author":1,"featured_media":895,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[],"class_list":["post-884","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tracht"],"_links":{"self":[{"href":"https:\/\/www.almliebe.com\/blog\/wp-json\/wp\/v2\/posts\/884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.almliebe.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.almliebe.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.almliebe.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.almliebe.com\/blog\/wp-json\/wp\/v2\/comments?post=884"}],"version-history":[{"count":5,"href":"https:\/\/www.almliebe.com\/blog\/wp-json\/wp\/v2\/posts\/884\/revisions"}],"predecessor-version":[{"id":914,"href":"https:\/\/www.almliebe.com\/blog\/wp-json\/wp\/v2\/posts\/884\/revisions\/914"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.almliebe.com\/blog\/wp-json\/wp\/v2\/media\/895"}],"wp:attachment":[{"href":"https:\/\/www.almliebe.com\/blog\/wp-json\/wp\/v2\/media?parent=884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.almliebe.com\/blog\/wp-json\/wp\/v2\/categories?post=884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.almliebe.com\/blog\/wp-json\/wp\/v2\/tags?post=884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}